{"id":3136,"count":1,"description":"","link":"https:\/\/cinemaeafins.com.br\/filmes\/ator\/lovell-adams-gray\/","name":"Lovell Adams-Gray","slug":"lovell-adams-gray","taxonomy":"ator","meta":[],"_links":{"self":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/ator\/3136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/ator"}],"about":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/taxonomies\/ator"}],"wp:post_type":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/posts?ator=3136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}