{"id":3155,"count":1,"description":"","link":"https:\/\/cinemaeafins.com.br\/filmes\/atriz\/aleksandra-kimaeva\/","name":"Aleksandra Kimaeva","slug":"aleksandra-kimaeva","taxonomy":"atriz","meta":[],"_links":{"self":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/atriz\/3155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/atriz"}],"about":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/taxonomies\/atriz"}],"wp:post_type":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/posts?atriz=3155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}