{"id":3199,"count":1,"description":"","link":"https:\/\/cinemaeafins.com.br\/filmes\/atriz\/kimberly-campbell\/","name":"Kimberly Campbell","slug":"kimberly-campbell","taxonomy":"atriz","meta":[],"_links":{"self":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/atriz\/3199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/atriz"}],"about":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/taxonomies\/atriz"}],"wp:post_type":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/posts?atriz=3199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}