{"id":241,"count":103,"description":"<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/07\/filmes-americanos-cinema-e-afins.webp\"><img class=\"aligncenter wp-image-3649 size-large\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/07\/filmes-americanos-cinema-e-afins-1024x536.webp\" alt=\"Tom Cruise como Maverick em cena cl\u00e1ssica do filme Top Gun \u2013 Ases Indom\u00e1veis (1986), um \u00edcone do cinema americano\" width=\"1024\" height=\"536\" \/><\/a>\r\n<p style=\"text-align: justify\">Explore os <strong data-start=\"225\" data-end=\"246\">filmes americanos<\/strong>, produzidos nos Estados Unidos da Am\u00e9rica, o principal polo cinematogr\u00e1fico do mundo. De cl\u00e1ssicos de Hollywood a produ\u00e7\u00f5es independentes premiadas, descubra t\u00edtulos que marcaram gera\u00e7\u00f5es e continuam moldando a hist\u00f3ria do cinema. Aqui voc\u00ea encontra <strong data-start=\"497\" data-end=\"526\">filmes dos Estados Unidos<\/strong> de todos os g\u00eaneros, d\u00e9cadas e estilos, com informa\u00e7\u00f5es completas sobre elenco, dire\u00e7\u00e3o, sinopse, trilha sonora e trailers.<\/p>","link":"https:\/\/cinemaeafins.com.br\/filmes\/pais\/estados-unidos-da-america\/","name":"Estados Unidos da Am\u00e9rica","slug":"estados-unidos-da-america","taxonomy":"pais","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/pais\/241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/pais"}],"about":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/taxonomies\/pais"}],"wp:post_type":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/posts?pais=241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}