{"id":4295,"date":"2025-08-28T01:02:53","date_gmt":"2025-08-28T04:02:53","guid":{"rendered":"https:\/\/cinemaeafins.com.br\/filmes\/?p=4295"},"modified":"2025-10-13T15:29:45","modified_gmt":"2025-10-13T18:29:45","slug":"nuremberg-2025","status":"publish","type":"post","link":"https:\/\/cinemaeafins.com.br\/filmes\/nuremberg-2025\/","title":{"rendered":"Nuremberg (2025)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\">[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: justify;\">A <a title=\"Sony Pictures Classics\" href=\"https:\/\/www.youtube.com\/@SonyPicturesClassics\" target=\"_blank\" rel=\"noopener\">Sony Pictures Classics<\/a> revelou um novo teaser trailer de &#8220;<strong>Nuremberg<\/strong>&#8220;, filme de guerra, estrelado por <strong>Russell Crowe<\/strong> (<a title=\"Mais sobre Kraven, o Ca\u00e7ador\" href=\"https:\/\/cinemaeafins.com.br\/kraven-o-cacador-2024\/\" target=\"_blank\" rel=\"noopener\">Kraven, o Ca\u00e7ador<\/a>) e <strong>Rami Malek<\/strong> (<a title=\"Mais sobre Opera\u00e7\u00e3o Vingan\u00e7a\" href=\"https:\/\/cinemaeafins.com.br\/filmes\/operacao-vinganca-2025\/\" target=\"_blank\" rel=\"noopener\">Opera\u00e7\u00e3o Vingan\u00e7a<\/a>). Assista;<\/p>\n<p><!--more--><\/p>\n<h2 style=\"text-align: center;\">Novo teaser de Nuremberg<\/h2>\n<div class=\"video-container\"><iframe title=\"Teaser oficial de Nuremberg\" src=\"https:\/\/www.youtube.com\/embed\/zCOiEVU3R9Q?si=DDwsFkE-qjl-1fkX\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><br \/>\n<\/iframe><\/div>\n[\/vc_column_text][vc_tta_tabs section_title_tag=&#8221;h2&#8243; style=&#8221;flat&#8221; color=&#8221;black&#8221; spacing=&#8221;3&#8243; gap=&#8221;2&#8243; alignment=&#8221;center&#8221; active_section=&#8221;1&#8243; no_fill_content_area=&#8221;true&#8221; css=&#8221;.vc_custom_1756353024200{background-color: #ffffff !important;}&#8221;][vc_tta_section title=&#8221;Sinopse&#8221; tab_id=&#8221;Sinopse&#8221;][vc_column_text css=&#8221;&#8221;]\n<div class=\"sinopse-bloco\">\n<h3 style=\"text-align: center;\">Sinopse<\/h3>\n<p class=\"conteudo-sinopse\" style=\"text-align: justify;\">Em Nuremberg, 1945, um psiquiatra americano avalia 22 nazistas aguardando julgamento por crimes de guerra. Sua proximidade com Hermann G\u00f6ring e sua busca para entender a natureza do mal o levam a um caminho sem volta.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p><!--more-->[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;Elenco&#8221; tab_id=&#8221;Elenco&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong>Russell Crowek<\/strong><\/span><br \/>\nHermann G\u00f6ring<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/russell-crowe.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4298\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/russell-crowe.webp\" alt=\"Russell Crowe\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/russell-crowe.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/russell-crowe-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong> Rami Malek<\/strong><\/span><br \/>\nDouglas Kelley<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/rami-malek.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4299 size-full\" title=\"Rami Malek\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/rami-malek.webp\" alt=\"Rami Malek\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/rami-malek.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/rami-malek-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong>Michael Shannon<\/strong><\/span><br \/>\nRobert H. Jackson<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/michael-shannon.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4300\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/michael-shannon.webp\" alt=\"Michael Shannon\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/michael-shannon.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/michael-shannon-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong>John Slattery<br \/>\n<\/strong><\/span>Coronel Burton C. Andrus<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/john-slattery.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4302\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/john-slattery.webp\" alt=\"John Slattery\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/john-slattery.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/john-slattery-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong> Colin Hanks<\/strong><\/span><br \/>\nDr. Gustav Gilbert<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/colin-hanks.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4186\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/colin-hanks.webp\" alt=\"Colin Hanks\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/colin-hanks.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/colin-hanks-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong>Richard E. Grant<br \/>\n<\/strong><\/span>Sir David Maxwell-Fyfe<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/07\/richard-e-grant.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3727\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/07\/richard-e-grant.webp\" alt=\"Richard E. Grant\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/07\/richard-e-grant.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/07\/richard-e-grant-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong> Leo Woodall<\/strong><\/span><br \/>\nSgt. Howie Triest<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/leo-woodall.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4303\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/leo-woodall.webp\" alt=\"Leo Woodall\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/leo-woodall.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/leo-woodall-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong> Lotte Verbeek<br \/>\n<\/strong><\/span>Emmy<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/lotte-verbeek.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4304\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/lotte-verbeek.webp\" alt=\"Lotte Verbeek \" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/lotte-verbeek.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/lotte-verbeek-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong> Wrenn Schmidt<br \/>\n<\/strong><\/span>Elsie<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/wrenn-schmidt.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4305\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/wrenn-schmidt.webp\" alt=\"Wrenn Schmidt\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/wrenn-schmidt.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/wrenn-schmidt-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong> Mark O&#8217;Brien<\/strong><\/span><br \/>\nCoronel John Amen<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/mark-o-brien.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4306\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/mark-o-brien.webp\" alt=\"Mark O'Brien\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/mark-o-brien.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/mark-o-brien-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong> Lydia Peckham<\/strong><\/span><br \/>\nLila<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/lydia-peckham.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4307\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/lydia-peckham.webp\" alt=\"Lydia Peckham\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/lydia-peckham.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/lydia-peckham-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong> Andreas Pietschmann<br \/>\n<\/strong><\/span>Rudolf Hess<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/andreas-pietschmann.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4308\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/andreas-pietschmann.webp\" alt=\"Andreas Pietschmann\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/andreas-pietschmann.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/andreas-pietschmann-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong> Steven Pacey<\/strong><\/span><br \/>\nGeneral Marshall<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/steven-pacey.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4309\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/steven-pacey.webp\" alt=\"Steven Pacey\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/steven-pacey.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/steven-pacey-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong> Dan Cade<\/strong><\/span><br \/>\nCorporal Jones<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/dan-cade.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4310\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/dan-cade.webp\" alt=\"Dan Cade\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/dan-cade.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/dan-cade-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><strong> Roderick Hill<\/strong><\/span><br \/>\nNome n\u00e3o revelado<br \/>\n<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/roderick-hill.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4311\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/roderick-hill.webp\" alt=\"Roderick Hill\" width=\"214\" height=\"317\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/roderick-hill.webp 214w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/roderick-hill-203x300.webp 203w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Equipe&#8221; tab_id=&#8221;Equipe&#8221;][vc_column_text css=&#8221;&#8221;]\n<article class=\"ficha-tecnica-estilo-tabela\" aria-labelledby=\"ficha-tecnica-title\">\n<header>\n<h2 id=\"ficha-tecnica-title\"><\/h2>\n<\/header>\n<section class=\"ficha-bloco produtores\" aria-labelledby=\"produtores-title\">\n<h3 id=\"produtores-title\"><strong>Produtores<\/strong><\/h3>\n<ul>\n<li>Nikolett Barabas<\/li>\n<li>Marc Bloomgarden<\/li>\n<li>Devon Boyd<\/li>\n<li>Dave Chapman<\/li>\n<li>John B. Crye<\/li>\n<li>Terrol Cummins<\/li>\n<li>G\u00e9za Deme<\/li>\n<li>Jack El-Hai<\/li>\n<li>Bradley J. Fischer<\/li>\n<li>George Freeman<\/li>\n<li>Arvind Gopwani<\/li>\n<li>B\u00e9la Hajnal<\/li>\n<li>Tam\u00e1s Hajnal<\/li>\n<li>Tim Hartnett<\/li>\n<li>Ivett Havasi<\/li>\n<li>Cherilyn Hawrysh<\/li>\n<li>Brett Keating<\/li>\n<li>Dorka Klim<\/li>\n<li>Istv\u00e1n Major<\/li>\n<li>Harrison Moore<\/li>\n<li>Paul Neinstein<\/li>\n<li>Sharon Paul<\/li>\n<li>W. Porter Payne Jr.<\/li>\n<li>Leia Peddie<\/li>\n<li>Annie Saperstein<\/li>\n<li>Brooke Saperstein<\/li>\n<li>Richard Saperstein<\/li>\n<li>Sandy Shenkman<\/li>\n<li>William Sherak<\/li>\n<li>Frank Smith<\/li>\n<li>Benjamin Tappan<\/li>\n<li>Dennis Trunfio<\/li>\n<li>Beau Turpin<\/li>\n<li>James Vanderbilt<\/li>\n<\/ul>\n<\/section>\n<section class=\"ficha-bloco trilha-sonora\" aria-labelledby=\"trilha-title\">\n<h3 id=\"trilha-title\"><strong>Trilha sonora<\/strong><\/h3>\n<ul>\n<li>Brian Tyler<\/li>\n<\/ul>\n<\/section>\n<section class=\"ficha-bloco fotografia\" aria-labelledby=\"fotografia-title\">\n<h3 id=\"fotografia-title\"><strong>Dire\u00e7\u00e3o de fotografia<\/strong><\/h3>\n<ul>\n<li>Dariusz Wolski<\/li>\n<\/ul>\n<\/section>\n<section class=\"ficha-bloco edicao\" aria-labelledby=\"edicao-title\">\n<h3 id=\"edicao-title\"><strong>Edi\u00e7\u00e3o<\/strong><\/h3>\n<ul>\n<li>Tom Eagles<\/li>\n<\/ul>\n<\/section>\n<section class=\"ficha-bloco direcao-elenco\" aria-labelledby=\"direcao-elenco-title\">\n<h3 id=\"direcao-elenco-title\"><strong>Dire\u00e7\u00e3o de elenco<\/strong><\/h3>\n<ul>\n<li>Ad\u00e9l Csemez<\/li>\n<li>Gr\u00e9ti Fellner<\/li>\n<li>Anna Kennedy<\/li>\n<li>Suse Marquardt<\/li>\n<li>John Papsidera<\/li>\n<\/ul>\n<\/section>\n<section class=\"ficha-bloco designer-producao\" aria-labelledby=\"designer-producao-title\">\n<h3 id=\"designer-producao-title\"><strong>Designer de Produ\u00e7\u00e3o<\/strong><\/h3>\n<ul>\n<li>Eve Stewart<\/li>\n<\/ul>\n<\/section>\n<section class=\"ficha-bloco diretores-arte\" aria-labelledby=\"diretores-arte-title\">\n<h3 id=\"diretores-arte-title\"><strong>Diretores de arte<\/strong><\/h3>\n<ul>\n<li>Julianna Cristescu<\/li>\n<li>Tibor L\u00e1z\u00e1r<\/li>\n<\/ul>\n<\/section>\n<section class=\"ficha-bloco figurino\" aria-labelledby=\"figurino-title\">\n<h3 id=\"figurino-title\"><strong>Figurino<\/strong><\/h3>\n<ul>\n<li>Bartholomew Cariss<\/li>\n<\/ul>\n<\/section>\n<section class=\"ficha-bloco producao\" aria-labelledby=\"producao-title\">\n<h3 id=\"producao-title\"><strong>Produ\u00e7\u00e3o<\/strong><\/h3>\n<ul>\n<li>Bluestone Entertainment<\/li>\n<li>Filmsquad<\/li>\n<li>Media Finance Capital<\/li>\n<li>Mythology Entertainment<\/li>\n<li>Sz\u00e9chenyi Funds<\/li>\n<li>Walden Media<\/li>\n<\/ul>\n<\/section>\n<\/article>\n[\/vc_column_text][\/vc_tta_section][vc_tta_section title=&#8221;Curiosidades&#8221; tab_id=&#8221;Curiosidades&#8221;][vc_column_text css=&#8221;&#8221;]\n<div class=\"ficha-tecnica-estilo-tabela\">\n<ul class=\"texto-justificado\">\n<li style=\"text-align: justify;\">O psiquiatra Douglas Kelley foi o autor do livro \u201c22 Cells in Nuremberg\u201d (22 Celas em Nuremberg), obra na qual relata suas experi\u00eancias pessoais durante os julgamentos de Nuremberg e suas intera\u00e7\u00f5es com alguns dos principais r\u00e9us. No cap\u00edtulo final, Kelley faz uma reflex\u00e3o inquietante: afirma ter identificado nos Estados Unidos de sua \u00e9poca sinais semelhantes aos que antecederam a ascens\u00e3o do regime nazista na Alemanha pr\u00e9-Segunda Guerra Mundial.\n<p style=\"text-align: justify;\">Ap\u00f3s sua atua\u00e7\u00e3o em Nuremberg, o m\u00e9dico passou a colaborar com os departamentos de pol\u00edcia de Berkeley e Oakland, na Calif\u00f3rnia. Sua fun\u00e7\u00e3o era entrevistar agentes da lei e avaliar seus perfis psicol\u00f3gicos, muitas vezes tra\u00e7ando paralelos entre os comportamentos observados e aqueles que havia estudado entre os acusados do regime nazista.<\/p>\n<p style=\"text-align: justify;\">Grande parte de suas pesquisas e registros est\u00e1 preservada at\u00e9 hoje nas bibliotecas da Universidade da Calif\u00f3rnia, em Berkeley, tornando-se fonte relevante para estudiosos da hist\u00f3ria, da psicologia e da criminologia.<\/p>\n<\/li>\n<li style=\"text-align: justify;\">Russell Crowe e Michael Shannon j\u00e1 haviam contracenado anteriormente em \u201cO Homem de A\u00e7o\u201d (Man of Steel, 2013), filme que marcou o in\u00edcio do Universo Estendido da DC nos cinemas. Na produ\u00e7\u00e3o dirigida por Zack Snyder, Crowe interpretou Jor-El, pai biol\u00f3gico de Superman, enquanto Shannon deu vida ao ic\u00f4nico vil\u00e3o General Zod.<\/li>\n<li style=\"text-align: justify;\">O elenco do filme re\u00fane nomes de peso em Hollywood. Entre eles, est\u00e3o dois vencedores do Oscar \u2014 Rami Malek e Russell Crowe \u2014 al\u00e9m de dois indicados \u00e0 estatueta: Michael Shannon e Richard E. Grant.<\/li>\n<\/ul>\n<\/div>\n[\/vc_column_text][\/vc_tta_section][\/vc_tta_tabs][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner css=&#8221;.vc_custom_1750999331472{background-color: #F5F5F5 !important;border-radius: 10px !important;}&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text css=&#8221;&#8221;]<a href=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/nuremberg-2025-1.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4313 size-medium\" src=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/nuremberg-2025-1-200x300.webp\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/nuremberg-2025-1-200x300.webp 200w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/nuremberg-2025-1-683x1024.webp 683w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/nuremberg-2025-1-768x1152.webp 768w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/nuremberg-2025-1-1024x1536.webp 1024w, https:\/\/cinemaeafins.com.br\/filmes\/wp-content\/uploads\/2025\/08\/nuremberg-2025-1.webp 1280w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text css=&#8221;&#8221;]<strong>T\u00edtulo original:\u00a0<\/strong>Nuremberg<br \/>\n<strong>Nacionalidade:\u00a0<\/strong><span class=\"that\">Estados Unidos da Am\u00e9rica<\/span><br \/>\n<b>G\u00eaneros: <\/b>Biografia, Drama, Guerra, Hist\u00f3ria, Suspense<strong><br \/>\nAno de produ\u00e7\u00e3o:\u00a0<\/strong>2025<strong><br \/>\nData de estreia:\u00a0<\/strong> 7 de novembro de 2025 (Cinema)<strong><br \/>\nDire\u00e7\u00e3o:\u00a0<\/strong>James Vanderbilt<strong><br \/>\nRoteiro:\u00a0<\/strong>Jack El-Hai, James Vanderbilt<br \/>\n<strong>Dura\u00e7\u00e3o:<\/strong> 2 h 28 min<br \/>\n<strong>Classifica\u00e7\u00e3o: <\/strong>PG-13<br \/>\n<b>Distribui\u00e7\u00e3o:\u00a0<\/b><a title=\"Site oficial Sony Pictures Classics\" href=\"https:\/\/www.sonyclassics.com\/\" target=\"_blank\" rel=\"noopener\">Sony Pictures Classics<\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;] A Sony Pictures Classics revelou um novo teaser trailer de &#8220;Nuremberg&#8220;, filme de guerra, estrelado por Russell Crowe (Kraven, o Ca\u00e7ador) e Rami Malek (Opera\u00e7\u00e3o Vingan\u00e7a). Assista; Novo teaser de Nuremberg [\/vc_column_text][vc_tta_tabs section_title_tag=&#8221;h2&#8243; style=&#8221;flat&#8221; color=&#8221;black&#8221; spacing=&#8221;3&#8243; gap=&#8221;2&#8243; alignment=&#8221;center&#8221; active_section=&#8221;1&#8243; no_fill_content_area=&#8221;true&#8221; css=&#8221;.vc_custom_1756353024200{background-color: #ffffff !important;}&#8221;][vc_tta_section title=&#8221;Sinopse&#8221; tab_id=&#8221;Sinopse&#8221;][vc_column_text css=&#8221;&#8221;] Sinopse Em Nuremberg, 1945, um psiquiatra americano &hellip;<\/p>\n","protected":false},"author":1,"featured_media":4297,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":77,"footnotes":""},"categories":[115,6,9,55,96,631],"tags":[],"diretor":[1213],"ator":[1209,1134,1211,1203,1204,1207,1202,1201,637,1212,1200,1210],"atriz":[1205,1208,1206],"ano":[240],"pais":[241],"genero":[],"compositor":[],"class_list":["post-4295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biografia","category-drama","category-filme","category-guerra","category-historia","category-suspense","diretor-james-vanderbilt","ator-andreas-pietschmann","ator-colin-hanks","ator-dan-cade","ator-john-slattery","ator-leo-woodall","ator-mark-obrien","ator-michael-shannon","ator-rami-malek","ator-richard-e-grant","ator-roderick-hill","ator-russell-crowe","ator-steven-pacey","atriz-lotte-verbeek","atriz-lydia-peckham","atriz-wrenn-schmidt","ano-240","pais-estados-unidos-da-america"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/posts\/4295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/comments?post=4295"}],"version-history":[{"count":0,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/posts\/4295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/media\/4297"}],"wp:attachment":[{"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/media?parent=4295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/categories?post=4295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/tags?post=4295"},{"taxonomy":"diretor","embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/diretor?post=4295"},{"taxonomy":"ator","embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/ator?post=4295"},{"taxonomy":"atriz","embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/atriz?post=4295"},{"taxonomy":"ano","embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/ano?post=4295"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/pais?post=4295"},{"taxonomy":"genero","embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/genero?post=4295"},{"taxonomy":"compositor","embeddable":true,"href":"https:\/\/cinemaeafins.com.br\/filmes\/wp-json\/wp\/v2\/compositor?post=4295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}